{"id":5106,"date":"2023-11-07T14:36:49","date_gmt":"2023-11-07T14:36:49","guid":{"rendered":"https:\/\/www.auxiliagroup.com\/k9-unit\/"},"modified":"2024-10-29T10:59:30","modified_gmt":"2024-10-29T10:59:30","slug":"k9-unit","status":"publish","type":"page","link":"https:\/\/www.auxiliagroup.com\/en\/k9-unit\/","title":{"rendered":"K9 Unit"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5106\" class=\"elementor elementor-5106 elementor-3194\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa4767d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa4767d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2dfb4f\" data-id=\"f2dfb4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50ad33c elementor-widget elementor-widget-spacer\" data-id=\"50ad33c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abca920 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abca920\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68ea0fa\" data-id=\"68ea0fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c532430 elementor-widget elementor-widget-text-editor\" data-id=\"c532430\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d36915c elementor-widget elementor-widget-text-editor\" data-id=\"d36915c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p><span style=\"font-weight: 400;\">A canine unit in a private security context consists of a <\/span><b>trained dog and<\/b> <span style=\"font-weight: 400;\">by its <\/span><b>handler<\/b><span style=\"font-weight: 400;\">. Questi team lavorano insieme per   <\/span><b>provide additional security<\/b> <span style=\"font-weight: 400;\">in many situations such as event surveillance, searching for explosives or narcotics, protecting sensitive areas, and searching for missing persons.<\/span><\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f64e306 elementor-widget elementor-widget-spacer\" data-id=\"f64e306\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5be4e3 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5be4e3\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c7f2236\" data-id=\"c7f2236\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b03fb27 elementor-widget elementor-widget-image\" data-id=\"b03fb27\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-1024x681.jpg\" class=\"attachment-large size-large wp-image-5026\" alt=\"\" srcset=\"https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-1024x681.jpg 1024w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-300x200.jpg 300w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-768x511.jpg 768w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-1536x1022.jpg 1536w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-2048x1363.jpg 2048w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-1000x665.jpg 1000w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-350x233.jpg 350w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-1052x700.jpg 1052w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/03\/03.6.1-K9_K9-1-TBD-601x400.jpg 601w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b7a48db\" data-id=\"b7a48db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a131a6f elementor-widget elementor-widget-image\" data-id=\"a131a6f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-1024x681.jpg\" class=\"attachment-large size-large wp-image-5032\" alt=\"\" srcset=\"https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-1024x681.jpg 1024w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-300x200.jpg 300w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-768x511.jpg 768w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-1536x1022.jpg 1536w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-2048x1362.jpg 2048w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-1000x665.jpg 1000w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-350x233.jpg 350w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-1052x700.jpg 1052w, https:\/\/www.auxiliagroup.com\/wp-content\/uploads\/2024\/04\/03.6.2-svc-K9-2-scaled-1-601x400.jpg 601w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9be7006 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9be7006\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a312660\" data-id=\"a312660\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d51659d elementor-widget elementor-widget-spacer\" data-id=\"d51659d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1c3752 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"e1c3752\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper-container\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-80de8e6 swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.auxiliagroup.com\/en\/?page_id=5060\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Do you have any questions?<\/div><div class=\"elementor-slide-description\"><p>Can our experts help you?<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Contact us<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89b848a elementor-widget elementor-widget-spacer\" data-id=\"89b848a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f31bc44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f31bc44\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01253d2\" data-id=\"01253d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b365328 elementor-widget elementor-widget-text-editor\" data-id=\"b365328\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.iubenda.com\/privacy-policy\/47487879\" class=\"iubenda-white iubenda-noiframe iubenda-embed iubenda-noiframe \" title=\"Privacy Policy \">Privacy Policy<\/a><script type=\"text\/javascript\">(function (w,d) {var loader = function () {var s = d.createElement(\"script\"), tag = d.getElementsByTagName(\"script\")[0]; s.src=\"https:\/\/cdn.iubenda.com\/iubenda.js\"; tag.parentNode.insertBefore(s,tag);}; if(w.addEventListener){w.addEventListener(\"load\", loader, false);}else if(w.attachEvent){w.attachEvent(\"onload\", loader);}else{w.onload = loader;>(window, document);<\/script>\n\n<a href=\"https:\/\/www.iubenda.com\/privacy-policy\/47487879\/cookie-policy\" class=\"iubenda-white iubenda-noiframe iubenda-embed iubenda-noiframe \" title=\"Cookie Policy \">Cookie Policy<\/a><script type=\"text\/javascript\">(function (w,d) {var loader = function () {var s = d.createElement(\"script\"), tag = d.getElementsByTagName(\"script\")[0]; s.src=\"https:\/\/cdn.iubenda.com\/iubenda.js\"; tag.parentNode.insertBefore(s,tag);}; if(w.addEventListener){w.addEventListener(\"load\", loader, false);}else if(w.attachEvent){w.attachEvent(\"onload\", loader);}else{w.onload = loader;>(window, document);<\/script>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A canine unit in a private security context consists of a trained dog and by its handler. Questi team lavorano insieme per provide additional security in many situations such as event surveillance, searching for explosives or narcotics, protecting sensitive areas, and searching for missing persons. Do you have any questions? Can our experts help you? [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5048,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/pages.php","meta":{"footnotes":""},"class_list":["post-5106","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/pages\/5106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/comments?post=5106"}],"version-history":[{"count":2,"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/pages\/5106\/revisions"}],"predecessor-version":[{"id":5114,"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/pages\/5106\/revisions\/5114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/media\/5048"}],"wp:attachment":[{"href":"https:\/\/www.auxiliagroup.com\/en\/wp-json\/wp\/v2\/media?parent=5106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}